{"id":13667,"date":"2021-12-21T07:10:45","date_gmt":"2021-12-21T07:10:45","guid":{"rendered":"https:\/\/charcoalmachines.com\/?p=13667"},"modified":"2023-06-16T18:07:55","modified_gmt":"2023-06-16T10:07:55","slug":"load-bearing-standard-of-compressed-wooden-pallets","status":"publish","type":"info","link":"https:\/\/charcoalmachines.com\/de\/load-bearing-standard-of-compressed-wooden-pallets\/","title":{"rendered":"Was ist die Tragf\u00e4higkeitsnorm f\u00fcr verpresste Holzpaletten?"},"content":{"rendered":"<p>Gepresste Holzpaletten haben aufgrund ihrer gro\u00dfen Tragf\u00e4higkeit eine breite Anwendungspalette. Sie werden h\u00e4ufig f\u00fcr Lagerung, Lieferung oder Pr\u00e4sentationspaletten verwendet, um gew\u00f6hnliche Holzpaletten zu ersetzen. <\/p>    <p>Holzpaletten werden zum Transportieren von G\u00fctern verwendet. Beim Transportieren von G\u00fctern ist sicherzustellen, dass die Holzpaletten intakt sind und eine bestimmte Festigkeit aufweisen. Wie k\u00f6nnen wir die Tragf\u00e4higkeit von Holzpaletten unterscheiden? Es gibt zwei Hauptpr\u00fcfstandards zur Unterscheidung der Tragf\u00e4higkeit von Holzpaletten: einer ist der Biege- und Druckfestigkeitstest, und der andere ist der Falltest.<\/p>    <figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/charcoalmachines.com\/wp-content\/uploads\/2021\/12\/wood-pallets-making-machine-for-shipping-to-Singapore.jpg\" alt=\"Holzpalettenherstellungsmaschine f\u00fcr den Versand nach Singapur\" class=\"wp-image-13669\"\/><figcaption class=\"wp-element-caption\">Holzpalettenherstellungsmaschine f\u00fcr den Versand nach Singapur<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\" id=\"h-features-of-compressed-wood-pallets\">Merkmale der komprimierten Holzpaletten<\/h2>    <p class=\"translation-block\">Gepresste Holzpaletten werden vom <strong><a href=\"https:\/\/charcoalmachines.com\/de\/compressed-wood-pallet-press-machine\/\">Holzpalettenhersteller<\/a><\/strong> geformt, und ihre Rohstoffe enthalten oft mehr als 85 % Holz und bis zu 15 % Harnstoffharz. Gepresste Holzpaletten haben in der Regel eine Vielzahl international anerkannter Standardgr\u00f6\u00dfen und -gewichte und zeichnen sich durch stabile Qualit\u00e4t und pr\u00e4zise Abmessungen aus. Im Vergleich zu gew\u00f6hnlichen Holzpaletten haben gepresste Holzpaletten kein Risiko, durch N\u00e4gel oder Schrauben besch\u00e4digt zu werden, und k\u00f6nnen leicht gestapelt und transportiert werden.<\/p>    <figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/charcoalmachines.com\/wp-content\/uploads\/2021\/12\/compressed-wood-pallets.jpg\" alt=\"Verpresste Holzpaletten\" class=\"wp-image-13668\"\/><figcaption class=\"wp-element-caption\">Verpresste Holzpaletten<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">Wie man die Tragf\u00e4higkeit von komprimierten Holzpaletten testet?<\/h2>    <p>Die Tragf\u00e4higkeitsnorm von Holzpaletten wird in der technischen Terminologie als Belastung bezeichnet. Die Belastung von Holzpaletten sind keine genauen Daten, sondern mehrere Datenbereiche oder Intervalle. Au\u00dferdem wird die Tragf\u00e4higkeit von Holzpaletten durch verschiedene Faktoren beeinflusst, abh\u00e4ngig von der spezifischen Anwendung. <\/p>    <p>Daher gibt es in der Branche keinen spezifischen Tragf\u00e4higkeitsstandard f\u00fcr Holzpaletten. Zun\u00e4chst ist die Einsatzumgebung von Holzpaletten unterschiedlich, und ihre Tragf\u00e4higkeit wird beeinflusst. <\/p>    <p>Wenn die Holzpalette horizontal auf einer harten Oberfl\u00e4che platziert wird und die G\u00fcter gleichm\u00e4\u00dfig auf der Holzpalette verteilt sind, nennt man das Gewicht, das die Holzpalette tragen kann, statische Belastung. Wenn die G\u00fcter gleichm\u00e4\u00dfig auf der Palette platziert sind, kann die Palette sich bewegen, und wir nennen das Gewicht, das eine Holzpalette tr\u00e4gt, dynamische Belastung.<\/p>    <figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/charcoalmachines.com\/wp-content\/uploads\/2021\/12\/wood-pallet-press-machine.jpg\" alt=\"Holzpalettenpressmaschine\"\/><figcaption class=\"wp-element-caption\">Holzpalettenpressmaschine<\/figcaption><\/figure>    <p class=\"translation-block\">Es gibt zwei Pr\u00fcfnormen, um die Tragf\u00e4higkeit von gepressten Holzpaletten zu bestimmen, die von <strong><a href=\"https:\/\/charcoalmachines.com\/de\/compressed-wood-pallet-press-machine\/\">Holzpalettenherstellermaschine<\/a><\/strong> hergestellt wurden: eine ist der Biegefestigkeitstest, und die andere ist der Druckfestigkeitstest.<\/p>    <ol class=\"wp-block-list\"> <li>In Form von einfach unterst\u00fctzten Balken wird die flache Ablage auf die untere St\u00fctze gelegt, und die Innenseite des Tr\u00e4gers ist mit den beiden inneren Seiten der unteren St\u00fctze ausgerichtet, wobei der Abstand zwischen den beiden inneren Seiten der unteren St\u00fctze die Unterst\u00fctzungsdistanz ist. Die unterst\u00fctzende untere St\u00fctze ist eine rechteckige Hohlbox, die durch Stumpfschwei\u00dfen von zwei Kanalstahl No. 10 gebildet wird, und ihre L\u00e4nge sollte etwas l\u00e4nger sein als die L\u00e4nge der Palette.<\/li>    <li>Zwei St\u00fctzen (obere St\u00fctzen) zum Laden werden auf die Schnur gelegt, wobei ein Viertel des Unterst\u00fctzungsabstands von der Mittellinie der Holzpalette zu beiden Seiten entfernt ist. Die beiden oberen St\u00fctzen, die zum Laden verwendet werden, bestehen aus nahtlosen Stahlrohren mit einem Au\u00dfendurchmesser von 76 mm und einer Wandst\u00e4rke von 6 mm, und ihre L\u00e4nge sollte etwas l\u00e4nger sein als die L\u00e4nge der Palette.<\/li>    <li>Der Biegefestigkeitstest von Holzpaletten kann mit einem Druckpr\u00fcfger\u00e4t von 3-5 Tonnen durchgef\u00fchrt werden. Weitere Messinstrumente sind ein Drehzahlmesser, ein Feuchtigkeitsgehaltmesser, ein Stahlma\u00dfband, eine Lotlinie usw. W\u00e4hrend des Tests wird die Palette auf die Druckpr\u00fcfmaschine gelegt, und eine konzentrierte Last wird durch die Druckplatte auf die obere St\u00fctze mit einer Ladegeschwindigkeit von 10 kg\/s aufgebracht. Wenn die Last 1,5-mal so hoch ist wie die Last der Holzpalette, wird die Durchbiegung in der Mitte der unteren Palette gemessen.<\/li> <\/ol>","protected":false},"excerpt":{"rendered":"<p>Gepresste Holzpaletten sind eine Transportstruktur, die G\u00fcter tr\u00e4gt, und k\u00f6nnen f\u00fcr einen stabilen Be- und Entladen von G\u00fctern mit Gabelstaplern, Palettenwagen usw. verwendet werden.<\/p>","protected":false},"author":1,"featured_media":13668,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"tags":[95],"info-type":[2],"class_list":["post-13667","info","type-info","status-publish","has-post-thumbnail","hentry","tag-wood-pallet-machine","info-type-faq"],"_links":{"self":[{"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/info\/13667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/types\/info"}],"author":[{"embeddable":true,"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/comments?post=13667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/media\/13668"}],"wp:attachment":[{"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/media?parent=13667"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/tags?post=13667"},{"taxonomy":"info-type","embeddable":true,"href":"https:\/\/charcoalmachines.com\/de\/wp-json\/wp\/v2\/info-type?post=13667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}