{"id":1769,"date":"2019-01-31T09:28:41","date_gmt":"2019-01-31T01:28:41","guid":{"rendered":"https:\/\/test.charcoalmachines.com\/?p=1769"},"modified":"2023-07-26T15:54:21","modified_gmt":"2023-07-26T07:54:21","slug":"wood-crusher-video","status":"publish","type":"info","link":"https:\/\/charcoalmachines.com\/fr\/wood-crusher-video\/","title":{"rendered":"Broyeur de bois avec une bonne efficacit\u00e9"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe loading=\"lazy\" title=\"Machine \u00e0 broyer le bois | Broyeur \u00e0 marteaux pour la sciure dans l&#039;usine de bois\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/h3PrXHgRXVo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div><figcaption class=\"wp-element-caption\">vid\u00e9o du broyeur de bois<\/figcaption><\/figure>    <ol class=\"wp-block-list\"> <li>De nombreuses mati\u00e8res premi\u00e8res peuvent \u00eatre broy\u00e9es par le broyeur, comme les copeaux de bois, les blocs de bois, la sciure, la paille et toutes sortes de coquilles, husks et coques.<\/li>    <li>Avec diff\u00e9rentes exigences pour la production de charbon de bois, le broyeur dispose de toutes sortes de mod\u00e8les et tailles.<\/li>    <li>Les principales pi\u00e8ces comprennent le marteau, l'arbre de coupe, l'entr\u00e9e et la sortie, structure simple et facile \u00e0 utiliser.<\/li>    <li>Ins\u00e9rez manuellement les blocs de bois dans l'entr\u00e9e.<\/li>    <li>L'arbre de coupe interne et le marteau broient ces blocs de bois et tamisent le mat\u00e9riau avec des tailles uniformes.<\/li>    <li>Les mat\u00e9riaux broy\u00e9s sont extraits dans le collecteur de poussi\u00e8re par le souffleur d'air.<\/li>    <li>Enfin, les mat\u00e9riaux finis sont \u00e9vacu\u00e9s par le collecteur de poussi\u00e8re et le processus suivant peut continuer.<\/li>    <li>Le broyeur est toujours utilis\u00e9 dans la ligne de production de charbon de bois.<b><\/b><\/li> <\/ol>    <p>Broyeur de copeaux\/blocs de bois avec une bonne efficacit\u00e9<\/p>    <p class=\"translation-block\"><strong><b>Autres noms<\/b><\/strong><\/p>    <p>Broyeur de paille ; broyeur de sciure ; broyeur de coque de noix de coco ; broyeur de bois ; broyeur de copeaux de bois ; broyeur de blocs de bois ; broyeur de coques d'arachide ; broyeur de coque de noix de coco ; broyeur de coquilles de noix de coco ;<\/p>    <p>Broyeur de paille de ma\u00efs ; broyeur de bagasse ; broyeur de paille de riz ; broyeur de bambou<\/p>    <p class=\"translation-block\"><strong><b>Description<\/b><\/strong><\/p>    <p>Le broyeur de copeaux de bois est principalement utilis\u00e9 pour les mat\u00e9riaux d'un diam\u00e8tre inf\u00e9rieur \u00e0 25 cm, comme les branches d'arbres, les copeaux de bois, les blocs de bois et autres mat\u00e9riaux.<\/p>    <p>Les mat\u00e9riaux apr\u00e8s la coupe de la lame du broyeur et \u00e0 travers les morceaux de marteau dans un diam\u00e8tre de 5-10 mm, puis \u00e0 travers le trou du tamis dans le collecteur de poussi\u00e8re. Enfin, les mat\u00e9riaux finis sont \u00e9vacu\u00e9s par le collecteur de poussi\u00e8re.<\/p>    <p>Le broyeur de copeaux\/blocs de bois est souvent utilis\u00e9 dans la ligne de production de charbon de bois, associ\u00e9 \u00e0 un s\u00e9choir, une machine \u00e0 briquettes de sciure et un four de carbonisation pour produire du charbon de haute qualit\u00e9.<\/p>    <p>Nous avons de nombreux types de broyeurs pour r\u00e9pondre \u00e0 vos diff\u00e9rents besoins. Diff\u00e9rents broyeurs conviennent \u00e0 diff\u00e9rentes mati\u00e8res premi\u00e8res. Nos clients des pays d'Asie du Sud-Est comme l'Indon\u00e9sie, la Malaisie, les Philippines, Singapour, le Vietnam ach\u00e8tent toujours l'ensemble de la ligne de production de charbon de bois pour produire du charbon \u00e0 grande \u00e9chelle.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le broyeur de copeaux de bois est principalement utilis\u00e9 pour les mat\u00e9riaux d'un diam\u00e8tre inf\u00e9rieur \u00e0 25 cm, comme les branches d'arbres, les copeaux de bois, les blocs de bois et autres mat\u00e9riaux.<\/p>","protected":false},"author":1,"featured_media":1843,"parent":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"tags":[116],"info-type":[30,130],"class_list":["post-1769","info","type-info","status-publish","has-post-thumbnail","hentry","tag-wood-crusher-machine","info-type-video","info-type-wood-recycling"],"_links":{"self":[{"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/info\/1769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/types\/info"}],"author":[{"embeddable":true,"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/comments?post=1769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/media\/1843"}],"wp:attachment":[{"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/media?parent=1769"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/tags?post=1769"},{"taxonomy":"info-type","embeddable":true,"href":"https:\/\/charcoalmachines.com\/fr\/wp-json\/wp\/v2\/info-type?post=1769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}